{"id":232571,"date":"2023-01-24T15:47:00","date_gmt":"2023-01-24T12:47:00","guid":{"rendered":"https:\/\/wordpress.mediadoma.com\/?p=232571"},"modified":"2023-01-24T15:47:24","modified_gmt":"2023-01-24T12:47:24","slug":"jquery-como-animar-a-rolagem-para-o-topo-e-a-rolagem-para-um-div","status":"publish","type":"post","link":"https:\/\/wordpress.mediadoma.com\/pt-pt\/jquery-como-animar-a-rolagem-para-o-topo-e-a-rolagem-para-um-div\/","title":{"rendered":"JQuery &#8211; Como animar a rolagem para o topo e a rolagem para um div?"},"content":{"rendered":"<p>javascript<\/p>\n<p><a href=\"https:\/\/helloacm.com\/jquery-examples-random-squares\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">JQuery<\/a> tem um prot\u00f3tipo de fun\u00e7\u00e3o \u00fatil <strong>animate que leva as primeiras propriedades<\/strong> <a href=\"https:\/\/helloacm.com\/how-to-make-first-letter-in-first-paragraph-big-in-wordpress-css-articles\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">CSS<\/a> finais como o primeiro par\u00e2metro, e a velocidade como o segundo par\u00e2metro, por exemplo, &quot;r\u00e1pido&quot;, &quot;lento&quot; ou o intervalo de tempo especificado. O terceiro par\u00e2metro \u00e9 um retorno de chamada opcional ap\u00f3s a anima\u00e7\u00e3o ser finalizado.<\/p>\n<pre><code>var properties = { color: red; };\n$('div').animate(properties, \"fast\", function() {});<\/code><\/pre>\n<p><a href=\"https:\/\/steakovercooked.com\/Welcome.Home\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Recentemente, no meu site pessoal<\/a>, redesenhei a perspectiva da p\u00e1gina para torn\u00e1-la totalmente <a href=\"https:\/\/wordpress.mediadoma.com\/pt-pt\/passos-simples-para-tornar-o-site-compativel-com-dispositivos-moveis-design-responsivo\/\" title=\"amig\u00e1vel ao usu\u00e1rio m\u00f3vel\">amig\u00e1vel ao usu\u00e1rio m\u00f3vel<\/a>. H\u00e1 dois links em posi\u00e7\u00f5es fixas da tela, &#8216;Navigation&#8217; e &#8216;Top&#8217;.<\/p>\n<h3>Navega\u00e7\u00e3o<\/h3>\n<p>O menu de navega\u00e7\u00e3o \u00e9 colocado ap\u00f3s o conte\u00fado principal da p\u00e1gina e, portanto, voc\u00ea precisaria definir um <strong>div<\/strong> com, por exemplo, id=&#8217;navigate&#8217;. Em seguida, adicione o seguinte c\u00f3digo <a href=\"https:\/\/helloacm.com\/jquery-examples\/random-squares\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">JQuery .<\/a><\/p>\n<pre><code>$(\"a[href='#navigate']\").click(function(){\n\u00a0 \u00a0 $(\"html, body\").stop().animate(\n\u00a0 \u00a0 \u00a0 \u00a0 {scrollTop:$(\"div#navigate\").offset().top}, \"slow\");\n\u00a0 \u00a0 \u00a0 \u00a0 return false;\n\u00a0 \u00a0 })\n});<\/code><\/pre>\n<h3>Topo<\/h3>\n<p>Voc\u00ea precisaria primeiro definir uma \u00e2ncora com, por exemplo,<\/p>\n<pre><code>&lt;a name='top'&gt;&lt;\/a&gt;<\/code><\/pre>\n<p>Coloque isso logo ap\u00f3s e adicione o seguinte c\u00f3digo <a href=\"https:\/\/helloacm.com\/how-to-invoke-apis-the-javascriptajax-example\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">JQuery :<\/a><\/p>\n<pre><code>$(\"a[href='#top']\").click(function(){\n\u00a0 \u00a0 $(\"html, body\").stop().animate(\n\u00a0 \u00a0 \u00a0 \u00a0 {scrollTop:0}, \"slow\");\n\u00a0 \u00a0 \u00a0 \u00a0 return false;\n\u00a0 \u00a0 })\n});<\/code><\/pre>\n<p>rolagem<\/p>\n<p><div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">Fonte de grava\u00e7\u00e3o:  <a target=\"_blank\" rel=\"noopener nofollow\" href=\"\/\/helloacm.com\" class=\"external external_icon\">helloacm.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JQuery \u2013 Como animar a rolagem para o topo e a rolagem para uma div?<\/p>\n","protected":false},"author":1,"featured_media":224394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[898,722,733,846,867],"tags":[1170],"class_list":["post-232571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-codigo-2","category-desenvolvedor","category-javascript-8","category-tutoriais","category-wordpress-8","tag-affiai-pt-pt"],"_links":{"self":[{"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts\/232571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=232571"}],"version-history":[{"count":0,"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts\/232571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/media\/224394"}],"wp:attachment":[{"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=232571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=232571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=232571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}