{"id":229282,"date":"2022-10-22T09:37:00","date_gmt":"2022-10-22T06:37:00","guid":{"rendered":"https:\/\/wordpress.mediadoma.com\/?p=229282"},"modified":"2022-11-09T06:17:28","modified_gmt":"2022-11-09T03:17:28","slug":"wordpress-contro-medium-e-davvero-importante","status":"publish","type":"post","link":"https:\/\/wordpress.mediadoma.com\/it\/wordpress-contro-medium-e-davvero-importante\/","title":{"rendered":"WordPress contro Medium: \u00e8 davvero importante?"},"content":{"rendered":"\n<p>Lo scorso fine settimana, ho passato del tempo a chiudere un gruppo di siti, esportare contenuti da un servizio a un altro, prepararmi a consolidare un paio di siti e persino chiudere alcuni siti.<\/p>\n<p>Ma la cosa numero uno che ha portato a uno strano feedback \u00e8 l&#8217;idea che ho scelto di <a href=\"https:\/\/tommcfarlin.com\/using-medium\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">archiviare i miei dati<\/a> da <a href=\"https:\/\/medium.com\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Medium<\/a> per prepararmi a spostarli su un sito basato su <a href=\"https:\/\/wordpress.oprg\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">WordPress .<\/a> Ci\u00f2 ha comportato alcuni strani punti WordPress rispetto a quelli medi da altri.<\/p>\n<p>Sinceramente, so che questo tipo di discussione non morir\u00e0 mai. Ma per ora sto divagando.<\/p>\n<p>E, suppongo, il motivo per cui \u00e8 strano \u00e8 che io, come molti che usano WordPress, voglio il controllo che deriva dal possedere i tuoi dati. Forse si tratta anche di giocare nella sandbox di qualcun altro, giusto?<\/p>\n<p>Ma c&#8217;\u00e8 un problema intrinseco nel rimanere con un solo CMS e trascurare ci\u00f2 che il resto del settore sta facendo.<\/p>\n<h2>WordPress contro Medium<\/h2>\n<p>Non conosco nessuno che si consideri uno sviluppatore web e lavori con WordPress e non apprezzi l&#8217;estendibilit\u00e0 che offre la piattaforma.<\/p>\n<p>Ma fai un passo indietro e guarda WordPress da 150.000 piedi. Questo software fa molto. Ed \u00e8 fantastico, vero? Anche la nuova pagina di destinazione [di bell&#8217;aspetto] per WordPress.org ammette che il software pu\u00f2 essere utilizzato per blog, siti e persino per lo sviluppo di applicazioni.<\/p>\n<p>La nuova homepage di WordPress.org.<\/p>\n<p>Forse questo \u00e8 un paragone ingiusto, ma \u00e8 molto raro che ci chiudiamo in un singolo genere o stile individuale di qualcosa in altre aree della nostra vita, non \u00e8 vero?<\/p>\n<ul>\n<li>Leggiamo narrativa e saggistica,<\/li>\n<li>Ascoltiamo punk, ambient, hard rock, hip-hop, elettronica e cos\u00ec via,<\/li>\n<li>Guardiamo fantascienza, dramma, thriller, commedia,<\/li>\n<li>Mangiamo americani, indiani, italiani, cinesi, giapponesi, ecc.,<\/li>\n<li>E cos\u00ec via.<\/li>\n<\/ul>\n<p>Hai capito il senso per\u00f2. Perch\u00e9, allora, quando si tratta di concorrenza, dovremmo limitarci a un unico attore in questo segmento di questo settore?<\/p>\n<p><a href=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-168090-61e7ad5cbbfe8.png\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-168090-61e7ad5cbbfe8.png\" alt=\"WordPress contro Medium: \u00e8 davvero importante?\" ><\/a><\/p>\n<p>La homepage media.<\/p>\n<p>La logica alla base \u00e8 questa: ci sono molte soluzioni innovative che vengono costruite, utilizzate e impiegate da molte, molte persone al di fuori dell&#8217;economia di WordPress.<\/p>\n<ul>\n<li>Perch\u00e9 non vedere cosa stanno facendo?<\/li>\n<li>Cosa c&#8217;\u00e8 nella loro economia che attrae cos\u00ec tante persone?<\/li>\n<li>Cosa stanno sbagliando (e cosa sbagliano)?<\/li>\n<\/ul>\n<p>In definitiva, quali sono le cose che possiamo studiare per riportare su WordPress per continuare a renderlo l&#8217;attore principale che \u00e8?<\/p>\n<h2>Prendi in prestito e riportalo indietro<\/h2>\n<p>E no, non sto parlando di cosa possiamo portare nel core (voglio dire, certo, alcuni possono, ma non \u00e8 la strada che scelgo di prendere).<\/p>\n<p>Invece, cosa possiamo fare con i nostri temi, i nostri plug-in o il nostro set generale di estensioni per aiutare a migliorare la piattaforma oltre a ci\u00f2 che fa oggi in modo che prenda le code di ispirazione da altri importanti attori di successo?<\/p>\n<p>Molte persone nel settore tecnologico amano citare Steve Jobs (<a href=\"http:\/\/quoteinvestigator.com\/2013\/03\/06\/artists-steal\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">citando qualcun altro<\/a> ):<\/p>\n<blockquote>\n<p>Buoni artisti copiano; grandi artisti rubano.<\/p>\n<\/blockquote>\n<p>Eppure, quando arriva il momento di prendere spunto dalla nostra competizione, ci rimproveriamo a vicenda per aver cercato di imparare, capire e forse anche migliorare le cose con cui lavoriamo principalmente.<\/p>\n<p>Infine, questo non ha lo scopo di essere difensivo n\u00e9 di fare di me un apologeta per un altro software. Invece, intende semplicemente affermare che, come sviluppatori web nello spazio dell&#8217;editoria, non penso che abbia senso essere tutto o niente.<\/p>\n<p>Pu\u00f2 andare in entrambe le direzioni se vogliamo che una piattaforma scelta abbia successo in una determinata area? Personalmente no, non credo. \u00c8 importante sapere cosa stanno facendo gli altri in modo da poter almeno tenere il passo.<\/p>\n<p>Altrimenti, corriamo il rischio di rimanere indietro.<\/p>\n<p>Inoltre, chi ha detto che scrivere per una piattaforma rispetto a un&#8217;altra sacrifichi comunque la propriet\u00e0 dei dati? Non possiamo semplicemente scrivere la nostra bozza in un editor di terze parti, salvarla, quindi copiarla su detta piattaforma quando arriva il momento di pubblicare le informazioni?<\/p>\n<p>Non so. Forse questo viola una sorta di mantra dell&#8217;editoria democratica per il quale non ho familiarit\u00e0. \ud83d\ude0f<\/p>\n<p><div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">Fonte di registrazione:  <a target=\"_blank\" rel=\"noopener nofollow\" href=\"\/\/tommcfarlin.com\" class=\"external external_icon\">tommcfarlin.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo spostamento dei dati da Medium a WordPress ha portato a una sorta di punti &#8220;WordPress contro Medium&#8221; da parte dei peer. Ma questo ha senso?<\/p>\n","protected":false},"author":1,"featured_media":223663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[678,865],"tags":[1168],"class_list":["post-229282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al-blog-2","category-wordpress-6","tag-affiai-it"],"_links":{"self":[{"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/posts\/229282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/comments?post=229282"}],"version-history":[{"count":0,"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/posts\/229282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/media\/223663"}],"wp:attachment":[{"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/media?parent=229282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/categories?post=229282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/it\/wp-json\/wp\/v2\/tags?post=229282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}