{"id":232912,"date":"2023-01-30T12:55:00","date_gmt":"2023-01-30T09:55:00","guid":{"rendered":"https:\/\/wordpress.mediadoma.com\/?p=232912"},"modified":"2023-02-01T10:59:25","modified_gmt":"2023-02-01T07:59:25","slug":"comment-deplacer-des-commentaires-dun-article-page-a-un-autre-dans-wordpress","status":"publish","type":"post","link":"https:\/\/wordpress.mediadoma.com\/fr\/comment-deplacer-des-commentaires-dun-article-page-a-un-autre-dans-wordpress\/","title":{"rendered":"Comment d\u00e9placer des commentaires d&rsquo;un article\/page \u00e0 un autre dans WordPress ?"},"content":{"rendered":"<p>Parfois, \u00e0 des fins de <a href=\"https:\/\/wordpress.mediadoma.com\/fr\/astuce-seo-comment-supprimer-les-liens-brises\/\" title=\"r\u00e9f\u00e9rencement\">r\u00e9f\u00e9rencement<\/a>, vous souhaitez d\u00e9placer quelques commentaires d&rsquo;un article\/page \u00e0 un autre dans <a href=\"https:\/\/wordpress.mediadoma.com\/fr\/comment-activer-amp-avec-wordpress-techniques-doptimisation-amp-avec-wordpress\/\" title=\"WordPress\">WordPress<\/a>. Ce n&rsquo;est pas int\u00e9gr\u00e9 \u00e0 WordPress, mais il existe une solution de contournement.<\/p>\n<h2>Comment d\u00e9placer des commentaires WordPress via SQL ?<\/h2>\n<p>Dans la page des commentaires de WordPress, vous connaissez l&rsquo;ID des commentaires et le post_id ou page_id, vous pouvez donc vous connecter \u00e0 PHPMyAdmin ou simplement \u00e0 la <a href=\"https:\/\/helloacm.com\/php-script-to-execute-mysql-statements-in-a-text-file\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">console MySQL<\/a> et \u00e9mettre la commande suivante pour d\u00e9placer un commentaire particulier (avec l&rsquo;ID de commentaire) vers une publication\/page sp\u00e9cifique .<\/p>\n<pre><code>update `wp_comments` set `comment_post_ID` = {TARGET_ID} where `comment_ID` = {COMMENT_ID};<\/code><\/pre>\n<p>Vous pouvez d\u00e9placer plusieurs commentaires \u00e0 la fois, en utilisant l&rsquo;instruction SQL in.<\/p>\n<pre><code>update `wp_comments` set `comment_post_ID` = {TARGET_ID} where `comment_ID` in ({COMMENT_ID}, {COMMENT_ID}, {COMMENT_ID} ...);<\/code><\/pre>\n<p>Vous pouvez \u00e9galement envisager d&rsquo;encapsuler le <a href=\"https:\/\/helloacm.com\/sql-coding-exercise-rank-scores\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">SQL<\/a> via <a href=\"https:\/\/helloacm.com\/how-to-unit-test-url-connectivity-via-phpunit\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">PHP<\/a> Script, ce qui vous donne plus de flexibilit\u00e9.<\/p>\n<h2>Comment d\u00e9placer les commentaires WordPress via le plugin ?<\/h2>\n<p>\u00c9crire du <a href=\"https:\/\/wordpress.mediadoma.com\/fr\/comment-repertorier-les-messages-les-plus-votes-en-une-annee-a-laide-de-sql\/\" title=\"SQL\">SQL<\/a> ou du PHP n&rsquo;est ni facile ni pratique pour tout le monde, alors voici un <a href=\"https:\/\/wordpress.mediadoma.com\/fr\/tutoriel-plugin-wordpress-comment-ecrire-le-premier-plugin\/\" title=\"plugin WordPress\">plugin WordPress<\/a> qui fait le travail.<\/p>\n<p><a href=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-155647-61e5661ba328e.jpg\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-155647-61e5661ba328e.jpg\" alt=\"Comment d\u00e9placer des commentaires d&#039;un article\/page \u00e0 un autre dans Wordpress ?\"><\/a><\/p>\n<p>d\u00e9placer-wp-commentaires-plugin<\/p>\n<p>Lors de l&rsquo;activation, vous pouvez ensuite acc\u00e9der \u00e0 la page des commentaires <a href=\"https:\/\/wordpress.mediadoma.com\/fr\/comment-rediriger-vers-la-publication-unique-dans-le-resultat-de-recherche-wordpress\/\" title=\"WordPress\">WordPress<\/a>, s\u00e9lectionner les commentaires que vous souhaitez d\u00e9placer.<\/p>\n<p><a href=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-155647-61e5661cb118e.jpg\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-155647-61e5661cb118e.jpg\" alt=\"Comment d\u00e9placer des commentaires d&#039;un article\/page \u00e0 un autre dans Wordpress ?\"><\/a><\/p>\n<p>comment-d\u00e9placer-wp-comments-plugin<\/p>\n<p>et, appliquez les options &quot;D\u00e9placer les commentaires&quot;, vous devez ensuite s\u00e9lectionner la publication\/page cible (destination) vers laquelle ces commentaires doivent aller (les post_titles sont r\u00e9pertori\u00e9s et vous pouvez rechercher les titres). Cliquez sur &quot;Mettre \u00e0 jour&quot; et tous les commentaires s\u00e9lectionn\u00e9s seront d\u00e9plac\u00e9s. Comme c&rsquo;est facile !<\/p>\n<p><div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">Source d&rsquo;enregistrement:  <a target=\"_blank\" rel=\"noopener nofollow\" href=\"\/\/helloacm.com\" class=\"external external_icon\">helloacm.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment d\u00e9placer les commentaires d&rsquo;un article\/page \u00e0 un autre dans WordPress ?<\/p>\n","protected":false},"author":1,"featured_media":223841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[893,993,801,841,862],"tags":[1167],"class_list":["post-232912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-code-2","category-marketing-de-contenu","category-php-3","category-tutoriels","category-wordpress-3","tag-affiai-fr"],"_links":{"self":[{"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/posts\/232912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/comments?post=232912"}],"version-history":[{"count":0,"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/posts\/232912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/media\/223841"}],"wp:attachment":[{"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/media?parent=232912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/categories?post=232912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/fr\/wp-json\/wp\/v2\/tags?post=232912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}