{"id":230323,"date":"2022-12-03T14:12:00","date_gmt":"2022-12-03T11:12:00","guid":{"rendered":"https:\/\/wordpress.mediadoma.com\/?p=230323"},"modified":"2022-11-09T21:07:56","modified_gmt":"2022-11-09T18:07:56","slug":"reflexionando-sobre-los-administradores-de-paquetes-modernos","status":"publish","type":"post","link":"https:\/\/wordpress.mediadoma.com\/es\/reflexionando-sobre-los-administradores-de-paquetes-modernos\/","title":{"rendered":"Reflexionando sobre los administradores de paquetes modernos"},"content":{"rendered":"\n<p>Hace poco estaba hablando con un amigo sobre todas las herramientas disponibles en el mercado para nosotros hoy (algunas gratuitas, otras de c\u00f3digo abierto) que nos ayudan con nuestras necesidades de desarrollo.<\/p>\n<p>Estos incluyen cosas como:<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/gruntjs.com\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Gru\u00f1ido<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/gulpjs.com\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Trago<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/yarnpkg.com\/en\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Hilo<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/codekitapp.com\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Kit de c\u00f3digo<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/getcomposer.org\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Compositor<\/a><\/strong><\/li>\n<li>y as\u00ed.<\/li>\n<\/ul>\n<p>Por supuesto, cada uno de los anteriores no es necesariamente comparable porque algunas son herramientas de front-end, otras son herramientas de back-end y hay algunas que ofrecen una especie de h\u00edbrido.<\/p>\n<p>Adem\u00e1s, algunos son premium, algunos son de c\u00f3digo abierto, algunos parecen estar abandonados y algunos incluso han dado lugar a procesos de compilaci\u00f3n rotos.<\/p>\n<p>Esto lleva a una serie de preguntas, varias de las cuales me gustar\u00eda cubrir. As\u00ed que aqu\u00ed, si nada m\u00e1s que reflexiones sobre los administradores de paquetes modernos, est\u00e1n las cosas en las que he estado pensando.<\/p>\n<h2>Administradores de paquetes modernos<\/h2>\n<p>Las preguntas que me vinieron a la mente (y que estuve discutiendo con dicho amigo) son las siguientes:<\/p>\n<ul>\n<li>\u00bfC\u00f3mo se supone que vamos a saber cu\u00e1l usar?<\/li>\n<li>cuando usarlos,<\/li>\n<li>y si vale la pena quedarse con ellos?<\/li>\n<\/ul>\n<p>Entonces pens\u00e9 en compartir mis pensamientos actuales sobre dichas herramientas y su aplicabilidad aqu\u00ed.<\/p>\n<h3>\u00bfCu\u00e1les usamos?<\/h3>\n<p>Es f\u00e1cil eludir esta respuesta y decir &quot;cualquiera que quieras&quot;, pero creo que la respuesta es un poco m\u00e1s matizada que eso.<\/p>\n<p>Por ejemplo, hay curvas de aprendizaje, paquetes, mantenimiento, etc. que vienen con cada uno de ellos. Esto no es algo bueno o malo, es lo natural de lo que son.<\/p>\n<p><a href=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-163159-61e74b8c11842.png\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-163159-61e74b8c11842.png\" alt=\"Reflexionando sobre los administradores de paquetes modernos\" ><\/a><\/p>\n<p>La pregunta que m\u00e1s me interesa hacer es &quot;\u00bfcu\u00e1l sirve mejor a mi equipo, mi proyecto y mis clientes?&quot; Y he aqu\u00ed por qu\u00e9:<\/p>\n<ol>\n<li>Si el equipo puede adoptar f\u00e1cilmente la utilidad, entonces hay casi cero fricci\u00f3n para ponerse en marcha con ella para su trabajo.<\/li>\n<li>Si funciona bien con el proyecto desde el principio, deber\u00eda facilitar el mantenimiento a medida que el proyecto crece y madura. Esto es importante porque, de lo contrario, corremos el riesgo de perder tiempo y esfuerzo valiosos para acelerar las cosas cuando cambia la utilidad (si cambia) y esto puede ser perjudicial para el cronograma de un proyecto.<\/li>\n<li>Creo que lo que mejor sirve al cliente es una de esas situaciones en las que \u00abel diablo est\u00e1 en los detalles&quot;. Eso es para que si los dos primeros est\u00e1n satisfechos, el cliente no ser\u00e1 m\u00e1s sabio. En segundo lugar, costar\u00eda menos tiempo, proporcionar\u00eda m\u00e1s valor y los mantendr\u00eda interesados \u200b\u200ben utilizarlo como proveedor de su servicio.<\/li>\n<\/ol>\n<p>Dicho esto, no creo que haya un solo caso de &quot;Esta es la utilidad que debe usar&quot; porque, nuevamente, no conozco los detalles de un proyecto determinado. Por lo tanto, no quiero prescribir una soluci\u00f3n cuando otra puede encajar en el caso.<\/p>\n<p>Y aqu\u00ed hay un ejemplo:<\/p>\n<p>He usado Gulp, CodeKit e Yarn en diferentes proyectos. \u00bfSer\u00eda bueno tener una sola herramienta para usar? \u00a1Por supuesto! Y cada uno puede hacer relativamente las mismas cosas que los dem\u00e1s.<\/p>\n<p>Pero la velocidad a la que se necesita para que algo funcione, la portabilidad y los paquetes disponibles difieren ligeramente, y si estoy trabajando en algo para m\u00ed, para un cliente, con un equipo o solo, todos son factores que se integran en la ecuaci\u00f3n. .<\/p>\n<p>Con el tiempo, creo que desarrollamos una intuici\u00f3n sobre cu\u00e1l puede ser mejor seg\u00fan los requisitos de un proyecto y dada la experiencia con cada una de las herramientas anteriores.<\/p>\n<p>Entonces, seguro, se requiere cierta inversi\u00f3n por adelantado para familiarizarse con la cantidad que considere adecuada para que sea beneficiosa para su equipo y sus esfuerzos, pero puede serle \u00fatil a medida que contin\u00faa avanzando como desarrollador.<\/p>\n<h3>\u00bfCu\u00e1ndo los usamos?<\/h3>\n<p>No creo que esta sea una pregunta tan dif\u00edcil de responder si ha hecho su debida diligencia al probarlos. De nuevo con la intuici\u00f3n, \u00bfno?<\/p>\n<p><a href=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-163159-61e74b90da956.png\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-163159-61e74b90da956.png\" alt=\"Reflexionando sobre los administradores de paquetes modernos\" ><\/a><\/p>\n<p>Pero aqu\u00ed est\u00e1 mi enfoque general:<\/p>\n<ul>\n<li>Si estoy trabajando solo o necesito concentrarme en algo r\u00e1pidamente, CodeKit es una buena soluci\u00f3n.<\/li>\n<li>Si estoy trabajando con un equipo y necesito tener algo r\u00e1pido, escalable y bien definido, Yarn es una buena opci\u00f3n.<\/li>\n<\/ul>\n<p>Todav\u00eda creo que vale la pena echarle un vistazo a Gulp, pero el desarrollo y los paquetes parecen haberse ralentizado. Grunt no parece estar en desarrollo en este momento, pero si funciona para usted y los paquetes que necesita, puede que no valga la pena cambiarlo ahora.<\/p>\n<p>De hecho, dir\u00eda que a menos que pueda proporcionar una raz\u00f3n s\u00f3lida para cambiar, \u00bfpor qu\u00e9 molestarse? La practicidad importa.<\/p>\n<h3>\u00bfVale la pena quedarse con ellos?<\/h3>\n<p>No s\u00e9. Quiero decir, la tecnolog\u00eda avanza muy r\u00e1pido y aparecen nuevas herramientas (que no necesariamente creo que debamos adoptar siempre), y luego se quedan por un tiempo.<\/p>\n<p><a href=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-163159-61e74b9636bfe.png\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/wordpress.mediadoma.com\/wp-content\/uploads\/2022\/01\/post-163159-61e74b9636bfe.png\" alt=\"Reflexionando sobre los administradores de paquetes modernos\" ><\/a><\/p>\n<p>Quiz\u00e1s se estancan. Quiz\u00e1s no alcancen una adopci\u00f3n generalizada. Tal vez est\u00e9n jubilados.<\/p>\n<p>Tal vez la respuesta m\u00e1s \u00f3ptima a esta pregunta es descubrir qu\u00e9 lo ayudar\u00e1 a resolver el problema de la manera m\u00e1s eficiente posible, que tambi\u00e9n est\u00e9 respaldado por una comunidad activa de desarrolladores y que usted y su equipo puedan adoptar m\u00e1s f\u00e1cilmente.<\/p>\n<h2>\u00bfLa l\u00ednea de fondo?<\/h2>\n<p>En todo caso, esta publicaci\u00f3n no es m\u00e1s que reflexiones personales sobre c\u00f3mo abordar el panorama en constante cambio de las herramientas de compilaci\u00f3n y los administradores de paquetes. Y es c\u00f3mo razonar cu\u00e1ndo a cu\u00e1l dado cierto tipo de problema.<\/p>\n<p>No necesariamente quiero una soluci\u00f3n \u00fanica porque creo que las opciones que tenemos fomentan m\u00e1s innovaci\u00f3n. Al mismo tiempo, puede introducir un nivel de fatiga cuando tienes que seguir el ritmo.<\/p>\n<p>Entonces, al menos, examine un subconjunto de las herramientas m\u00e1s populares (quiz\u00e1s como una estrella en GitHub como una m\u00e9trica \u00fatil) y luego contin\u00fae desde all\u00ed.<\/p>\n<p><div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">Fuente de grabaci\u00f3n:  <a target=\"_blank\" rel=\"noopener nofollow\" href=\"\/\/tommcfarlin.com\" class=\"external external_icon\">tommcfarlin.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esto lleva a una serie de preguntas, varias de las cuales me gustar\u00eda cubrir. As\u00ed que aqu\u00ed, si nada m\u00e1s que reflexiones sobre los administradores de paquetes modernos, est\u00e1n las cosas en las que he estado pensando.<\/p>\n","protected":false},"author":1,"featured_media":223872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[716,800,840],"tags":[1172],"class_list":["post-230323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollador","category-php-2","category-tutoriales","tag-affiai-es"],"_links":{"self":[{"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/posts\/230323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/comments?post=230323"}],"version-history":[{"count":0,"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/posts\/230323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/media\/223872"}],"wp:attachment":[{"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/media?parent=230323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/categories?post=230323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.mediadoma.com\/es\/wp-json\/wp\/v2\/tags?post=230323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}